{"id":119,"date":"2021-01-22T00:38:36","date_gmt":"2021-01-21T23:38:36","guid":{"rendered":"https:\/\/wordpress.dexten.com\/?page_id=119"},"modified":"2021-04-08T21:51:50","modified_gmt":"2021-04-08T19:51:50","slug":"about-us","status":"publish","type":"page","link":"https:\/\/www.dexten.com\/index.php\/about-us\/","title":{"rendered":"About us"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"119\" class=\"elementor elementor-119\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c6ced16 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c6ced16\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-123a13ce\" data-id=\"123a13ce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a696941 elementor-widget elementor-widget-spacer\" data-id=\"a696941\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ece3a8 elementor-widget elementor-widget-heading\" data-id=\"1ece3a8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">A strong partnership...<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b59df7d elementor-widget elementor-widget-text-editor\" data-id=\"5b59df7d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><p><!-- wp:paragraph --><\/p>\n<p>Founded in 2009, DEXTEN is a leading supplier of materials for fiber optic cables with a logistic warehouse located 50km from north of Paris.\u00a0<\/p>\n<p>Our history is based on a strong partnership with the SUHIL company which is a major manufacturer based in South-Korea and Vietnam. We are the SUHIL exclusive distributor in Europe, Maghreb and Turkey since 2009.\u00a0<\/p>\n<p><!-- \/wp:paragraph --><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-466915c elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"466915c\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.dexten.com\/wp-content\/uploads\/2021\/02\/1-300x225.jpg\" alt=\"1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.dexten.com\/wp-content\/uploads\/2021\/02\/2-300x225.jpg\" alt=\"2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.dexten.com\/wp-content\/uploads\/2021\/02\/IMG_3528-300x225.jpg\" alt=\"IMG_3528\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.dexten.com\/wp-content\/uploads\/2021\/02\/IMG_3539-300x225.jpg\" alt=\"IMG_3539\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.dexten.com\/wp-content\/uploads\/2021\/02\/IMG_3541-300x225.jpg\" alt=\"IMG_3541\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.dexten.com\/wp-content\/uploads\/2021\/02\/IMG_3550-300x225.jpg\" alt=\"IMG_3550\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.dexten.com\/wp-content\/uploads\/2021\/02\/IMG_3567-300x225.jpg\" alt=\"IMG_3567\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.dexten.com\/wp-content\/uploads\/2021\/02\/IMG_3580-300x225.jpg\" alt=\"IMG_3580\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.dexten.com\/wp-content\/uploads\/2021\/02\/IMG_E3574-300x225.jpg\" alt=\"IMG_E3574\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i class=\"eicon-chevron-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i class=\"eicon-chevron-right\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbeda4d elementor-widget elementor-widget-heading\" data-id=\"bbeda4d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">A wide range of cable materials...<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ec1ed9 elementor-widget elementor-widget-text-editor\" data-id=\"0ec1ed9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><p>Our lead material is FRP \u00a0and we also offer Monofilament Fillers,\u00a0<span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">Technical Yarns<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">\u00a0and HDPE Coated Steel WIres. Our whole range of materials is manufactured by SUHIL itself (no trading) so that means that we fully master the quality and the supply chain of our offered materials.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-653cc9d elementor-widget elementor-widget-heading\" data-id=\"653cc9d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">To deliver the best customer service flexibly...<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f3a98b elementor-widget elementor-widget-text-editor\" data-id=\"3f3a98b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><p>We have significant materials on stock with regular replenishments from South-Korea and Vietnam. We may of course customize our stocks in accordance with your needs with safety stocks to avoid any shortage. We have also rewinding lines to customize packaging according to your specifications. For your huge demands we may also deliver you directly from South-Korea or Vietnam to reduce your cost.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>A strong partnership&#8230; Founded in 2009, DEXTEN is a leading supplier of materials for fiber optic cables with a logistic warehouse located 50km from north of Paris.\u00a0 Our history is based on a strong partnership with the SUHIL company which is a major manufacturer based in South-Korea and Vietnam. We are the SUHIL exclusive distributor [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/www.dexten.com\/index.php\/wp-json\/wp\/v2\/pages\/119"}],"collection":[{"href":"https:\/\/www.dexten.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dexten.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dexten.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dexten.com\/index.php\/wp-json\/wp\/v2\/comments?post=119"}],"version-history":[{"count":26,"href":"https:\/\/www.dexten.com\/index.php\/wp-json\/wp\/v2\/pages\/119\/revisions"}],"predecessor-version":[{"id":888,"href":"https:\/\/www.dexten.com\/index.php\/wp-json\/wp\/v2\/pages\/119\/revisions\/888"}],"wp:attachment":[{"href":"https:\/\/www.dexten.com\/index.php\/wp-json\/wp\/v2\/media?parent=119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}